{"id":9,"name":"Irena \u0160tamfelj","url":"","description":"","link":"https:\/\/www.domenca.com\/blog\/author\/irena\/","slug":"irena","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/33df20fe3d1d619b3a267e2e531096e7814882d9fa5ed601f6bde12a04b56486?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/33df20fe3d1d619b3a267e2e531096e7814882d9fa5ed601f6bde12a04b56486?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/33df20fe3d1d619b3a267e2e531096e7814882d9fa5ed601f6bde12a04b56486?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Irena \u0160tamfelj, Author at Domenca.com Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.domenca.com\/blog\/author\/irena\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Irena \u0160tamfelj, Author at Domenca.com Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.domenca.com\/blog\/author\/irena\/\" \/>\n<meta property=\"og:site_name\" content=\"Domenca.com Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/1d81f09ae4b42fb7f192ba329349ea5f?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/author\\\/irena\\\/\",\"url\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/author\\\/irena\\\/\",\"name\":\"Irena \u0160tamfelj, Author at Domenca.com Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/author\\\/irena\\\/#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.domenca.com\\\/blog\\\/author\\\/irena\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/author\\\/irena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Irena \u0160tamfelj\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/\",\"name\":\"Domenca.com Blog\",\"description\":\"Domenca Blog\",\"alternateName\":\"Domenca Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sl-SI\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/#\\\/schema\\\/person\\\/f697fc9ec20978b588cf7a987ee3c012\",\"name\":\"Irena \u0160tamfelj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33df20fe3d1d619b3a267e2e531096e7814882d9fa5ed601f6bde12a04b56486?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33df20fe3d1d619b3a267e2e531096e7814882d9fa5ed601f6bde12a04b56486?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33df20fe3d1d619b3a267e2e531096e7814882d9fa5ed601f6bde12a04b56486?s=96&d=mm&r=g\",\"caption\":\"Irena \u0160tamfelj\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.domenca.com\\\/blog\\\/author\\\/irena\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Irena \u0160tamfelj, Author at Domenca.com Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.domenca.com\/blog\/author\/irena\/","og_locale":"sl_SI","og_type":"profile","og_title":"Irena \u0160tamfelj, Author at Domenca.com Blog","og_url":"https:\/\/www.domenca.com\/blog\/author\/irena\/","og_site_name":"Domenca.com Blog","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/1d81f09ae4b42fb7f192ba329349ea5f?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/www.domenca.com\/blog\/author\/irena\/","url":"https:\/\/www.domenca.com\/blog\/author\/irena\/","name":"Irena \u0160tamfelj, Author at Domenca.com Blog","isPartOf":{"@id":"https:\/\/www.domenca.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.domenca.com\/blog\/author\/irena\/#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.domenca.com\/blog\/author\/irena\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.domenca.com\/blog\/author\/irena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.domenca.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Archives for Irena \u0160tamfelj"}]},{"@type":"WebSite","@id":"https:\/\/www.domenca.com\/blog\/#website","url":"https:\/\/www.domenca.com\/blog\/","name":"Domenca.com Blog","description":"Domenca Blog","alternateName":"Domenca Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.domenca.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sl-SI"},{"@type":"Person","@id":"https:\/\/www.domenca.com\/blog\/#\/schema\/person\/f697fc9ec20978b588cf7a987ee3c012","name":"Irena \u0160tamfelj","image":{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/secure.gravatar.com\/avatar\/33df20fe3d1d619b3a267e2e531096e7814882d9fa5ed601f6bde12a04b56486?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33df20fe3d1d619b3a267e2e531096e7814882d9fa5ed601f6bde12a04b56486?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33df20fe3d1d619b3a267e2e531096e7814882d9fa5ed601f6bde12a04b56486?s=96&d=mm&r=g","caption":"Irena \u0160tamfelj"},"mainEntityOfPage":{"@id":"https:\/\/www.domenca.com\/blog\/author\/irena\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.domenca.com\/blog\/wp-json\/wp\/v2\/users\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.domenca.com\/blog\/wp-json\/wp\/v2\/users"}]}}