{"id":4219,"date":"2020-04-16T08:37:26","date_gmt":"2020-04-16T08:37:26","guid":{"rendered":"https:\/\/www.domenca.com\/podpora\/?post_type=kb&#038;p=4219"},"modified":"2025-03-14T13:24:31","modified_gmt":"2025-03-14T13:24:31","slug":"namescanje-node-js-aplikacij","status":"publish","type":"kb","link":"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/","title":{"rendered":"Name\u0161\u010danje node.js aplikacij"},"content":{"rendered":"<p>V cPanel nadzorni plo\u0161\u010di lahko node.js aplikacijo namestite s pomo\u010djo orodja Setup Node.js App, ki ga najdete pod razdelkom Software.<\/p>\n<p>1. Kliknite na ikono <strong>Setup Node.js App<\/strong>, nato na gumb <strong>Create Application<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4227\" src=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1.png\" alt=\"\" width=\"652\" height=\"81\" srcset=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1.png 768w, https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1-300x37.png 300w\" sizes=\"auto, (max-width: 652px) 100vw, 652px\" \/><\/p>\n<p>2. Izpolnite vnosna polja namestitvenega obrazca.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4226\" src=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js1-768x460-1.png\" alt=\"\" width=\"655\" height=\"392\" srcset=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js1-768x460-1.png 768w, https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js1-768x460-1-300x180.png 300w\" sizes=\"auto, (max-width: 655px) 100vw, 655px\" \/><\/p>\n<p>&#8211; Node.js version: izberite \u017eeleno verzijo s spustnega menuja.<br \/>\n&#8211; Application mode: izberite Development ali Production. Development je lahko kasneje spremenjen v Production.<br \/>\n&#8211; Application root &#8211; lokacija datotek aplikacije v datote\u010dnem sistemu. navedbo \/home\/username lahko izpustite.<\/p>\n<span class=\"mkb-shortcode-container\">\t\t<div class=\"mkb-info\">\n\t\t\t<div class=\"mkb-info__icon\">\n\t\t\t\t<i class=\"fa fa-info-circle fa-lg\"><\/i>\n\t\t\t<\/div>\n\t\t\t<div class=\"mkb-info__content\">\n\t\t\t\tTipi\u010dne lokacije korenske mape aplikacije so \/home\/username\/imeaplikacije oziroma \/home\/username\/apps\/imeaplikacije. Namestitev korenske mape aplikacije v domensko korensko mapo, recimo v public_html, odsvetujemo.\t\t\t<\/div>\n\t\t<\/div>\n\t<\/span>\n<p>&#8211; Application URL &#8211; spletni naslov aplikacije.<br \/>\n&#8211; Application startup file &#8211; inicialna datoteka, ki bo zagnana ob zagonu aplikacije.<\/p>\n<p>3. Kliknite Create.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4225\" src=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js2-768x95-1.png\" alt=\"\" width=\"660\" height=\"82\" srcset=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js2-768x95-1.png 768w, https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js2-768x95-1-300x37.png 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/p>\n<p>4. Kliknite <strong>Open<\/strong> za ogled aplikacije. Testno se vanjo namesti t.i. sample vsebina, zato ob ogledu v brskalniku vidite:<\/p>\n<pre>It works!\r\n\r\nNodeJS 10.19.0<\/pre>\n<p>Ko je aplikacija name\u0161\u010dena, lahko okolje nadgradite s package.json file in npm package managerjem. To storite po naslednjem postopku.<\/p>\n<h3>Ustvarite package.json<\/h3>\n<p>1. V razdelku <strong>Files<\/strong> kliknite na <strong>File Manager<\/strong>.<\/p>\n<p>2. V levem stolpcu kliknite na korensko mapo aplikacije.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4224\" src=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-File-Manager-v3.png\" alt=\"\" width=\"277\" height=\"275\" srcset=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-File-Manager-v3.png 277w, https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-File-Manager-v3-150x150.png 150w, https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-File-Manager-v3-100x100.png 100w\" sizes=\"auto, (max-width: 277px) 100vw, 277px\" \/><\/p>\n<p>3. Ustvarite novo datoteko s klikom na <strong>+File.<\/strong><\/p>\n<p>4. V pojavnem oknu New File datoteko poimenujte package.json in kliknite na <strong>Create New File.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4223\" src=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-File-Manager-v31.png\" alt=\"\" width=\"447\" height=\"220\" srcset=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-File-Manager-v31.png 447w, https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-File-Manager-v31-300x148.png 300w\" sizes=\"auto, (max-width: 447px) 100vw, 447px\" \/><\/p>\n<p>5. Z desnim mi\u0161kinim gumbom kliknite na package.json in izberite Edit.<\/p>\n<p>6. V urejevalnik vnesite testno vsebino:<\/p>\n<pre>{\r\n\"name\": \"app\",\r\n\"version\": \"1.0.0\",\r\n\"description\": \"My App\",\r\n\"main\": \"app.js\",\r\n\"scripts\": {\r\n\"test\": \"echo \\\"Error: no test specified\\\" &amp;&amp; exit 1\"\r\n},\r\n\"author\": \"\",\r\n\"license\": \"ISC\"\r\n}<\/pre>\n<p>8. Shranite spremembe s klikom na <strong>Save Changes.<\/strong><\/p>\n<h4>Namestitev NPM<\/h4>\n<p>1. V razdelku Software kliknite na Setup Node.js App, da odprete Node.js selector.<\/p>\n<p>2. V tabeli <strong>Actions<\/strong> razdelka <strong>Web Applications list<\/strong> kliknite na svin\u010dnik.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4222\" src=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js3.png\" alt=\"\" width=\"319\" height=\"88\" srcset=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js3.png 319w, https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js3-300x83.png 300w\" sizes=\"auto, (max-width: 319px) 100vw, 319px\" \/><\/p>\n<p>3. Kliknite na <strong>Run NPM Install.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4221\" src=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js4-768x86-1.png\" alt=\"\" width=\"768\" height=\"86\" srcset=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js4-768x86-1.png 768w, https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js4-768x86-1-300x34.png 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>4. Instalacija NPM se za\u017eene in prika\u017ee zelen indikator ob uspe\u0161ni namestitvi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V cPanel nadzorni plo\u0161\u010di lahko node.js aplikacijo namestite s pomo\u010djo orodja Setup Node.js App, ki ga najdete pod razdelkom Software. 1. Kliknite na ikono Setup Node.js App, nato na gumb Create Application. 2. Izpolnite vnosna polja namestitvenega obrazca. &#8211; Node.js version: izberite \u017eeleno verzijo s spustnega menuja. &#8211; Application mode: izberite Development ali Production. Development [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"kbtopic":[130],"kbtag":[],"class_list":["post-4219","kb","type-kb","status-publish","hentry","kbtopic-ostalo-cpanel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Name\u0161\u010danje node.js aplikacij - Podpora domenca.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Name\u0161\u010danje node.js aplikacij - Podpora domenca.com\" \/>\n<meta property=\"og:description\" content=\"V cPanel nadzorni plo\u0161\u010di lahko node.js aplikacijo namestite s pomo\u010djo orodja Setup Node.js App, ki ga najdete pod razdelkom Software. 1. Kliknite na ikono Setup Node.js App, nato na gumb Create Application. 2. Izpolnite vnosna polja namestitvenega obrazca. &#8211; Node.js version: izberite \u017eeleno verzijo s spustnega menuja. &#8211; Application mode: izberite Development ali Production. Development [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/\" \/>\n<meta property=\"og:site_name\" content=\"Podpora domenca.com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-14T13:24:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"95\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/kb\\\/namescanje-node-js-aplikacij\\\/\",\"url\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/kb\\\/namescanje-node-js-aplikacij\\\/\",\"name\":\"Name\u0161\u010danje node.js aplikacij - Podpora domenca.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/kb\\\/namescanje-node-js-aplikacij\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/kb\\\/namescanje-node-js-aplikacij\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1.png\",\"datePublished\":\"2020-04-16T08:37:26+00:00\",\"dateModified\":\"2025-03-14T13:24:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/kb\\\/namescanje-node-js-aplikacij\\\/#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/kb\\\/namescanje-node-js-aplikacij\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/kb\\\/namescanje-node-js-aplikacij\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1.png\",\"contentUrl\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1.png\",\"width\":768,\"height\":95},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/kb\\\/namescanje-node-js-aplikacij\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Name\u0161\u010danje node.js aplikacij\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/#website\",\"url\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/\",\"name\":\"Podpora domenca.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sl-SI\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/#organization\",\"name\":\"Podpora domenca.com\",\"url\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-dmc_podpora_2025.png\",\"contentUrl\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-dmc_podpora_2025.png\",\"width\":395,\"height\":82,\"caption\":\"Podpora domenca.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.domenca.com\\\/podpora\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Name\u0161\u010danje node.js aplikacij - Podpora domenca.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/","og_locale":"sl_SI","og_type":"article","og_title":"Name\u0161\u010danje node.js aplikacij - Podpora domenca.com","og_description":"V cPanel nadzorni plo\u0161\u010di lahko node.js aplikacijo namestite s pomo\u010djo orodja Setup Node.js App, ki ga najdete pod razdelkom Software. 1. Kliknite na ikono Setup Node.js App, nato na gumb Create Application. 2. Izpolnite vnosna polja namestitvenega obrazca. &#8211; Node.js version: izberite \u017eeleno verzijo s spustnega menuja. &#8211; Application mode: izberite Development ali Production. Development [&hellip;]","og_url":"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/","og_site_name":"Podpora domenca.com","article_modified_time":"2025-03-14T13:24:31+00:00","og_image":[{"width":768,"height":95,"url":"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/","url":"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/","name":"Name\u0161\u010danje node.js aplikacij - Podpora domenca.com","isPartOf":{"@id":"https:\/\/www.domenca.com\/podpora\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/#primaryimage"},"image":{"@id":"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/#primaryimage"},"thumbnailUrl":"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1.png","datePublished":"2020-04-16T08:37:26+00:00","dateModified":"2025-03-14T13:24:31+00:00","breadcrumb":{"@id":"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/"]}]},{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/#primaryimage","url":"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1.png","contentUrl":"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2020\/04\/Screenshot_2020-04-16-cPanel-Node-js-768x95-1.png","width":768,"height":95},{"@type":"BreadcrumbList","@id":"https:\/\/www.domenca.com\/podpora\/kb\/namescanje-node-js-aplikacij\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.domenca.com\/podpora\/"},{"@type":"ListItem","position":2,"name":"Name\u0161\u010danje node.js aplikacij"}]},{"@type":"WebSite","@id":"https:\/\/www.domenca.com\/podpora\/#website","url":"https:\/\/www.domenca.com\/podpora\/","name":"Podpora domenca.com","description":"","publisher":{"@id":"https:\/\/www.domenca.com\/podpora\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.domenca.com\/podpora\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sl-SI"},{"@type":"Organization","@id":"https:\/\/www.domenca.com\/podpora\/#organization","name":"Podpora domenca.com","url":"https:\/\/www.domenca.com\/podpora\/","logo":{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/www.domenca.com\/podpora\/#\/schema\/logo\/image\/","url":"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2025\/03\/cropped-dmc_podpora_2025.png","contentUrl":"https:\/\/www.domenca.com\/podpora\/wp-content\/uploads\/2025\/03\/cropped-dmc_podpora_2025.png","width":395,"height":82,"caption":"Podpora domenca.com"},"image":{"@id":"https:\/\/www.domenca.com\/podpora\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.domenca.com\/podpora\/wp-json\/wp\/v2\/kb\/4219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.domenca.com\/podpora\/wp-json\/wp\/v2\/kb"}],"about":[{"href":"https:\/\/www.domenca.com\/podpora\/wp-json\/wp\/v2\/types\/kb"}],"author":[{"embeddable":true,"href":"https:\/\/www.domenca.com\/podpora\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.domenca.com\/podpora\/wp-json\/wp\/v2\/comments?post=4219"}],"version-history":[{"count":5,"href":"https:\/\/www.domenca.com\/podpora\/wp-json\/wp\/v2\/kb\/4219\/revisions"}],"predecessor-version":[{"id":7187,"href":"https:\/\/www.domenca.com\/podpora\/wp-json\/wp\/v2\/kb\/4219\/revisions\/7187"}],"wp:attachment":[{"href":"https:\/\/www.domenca.com\/podpora\/wp-json\/wp\/v2\/media?parent=4219"}],"wp:term":[{"taxonomy":"kbtopic","embeddable":true,"href":"https:\/\/www.domenca.com\/podpora\/wp-json\/wp\/v2\/kbtopic?post=4219"},{"taxonomy":"kbtag","embeddable":true,"href":"https:\/\/www.domenca.com\/podpora\/wp-json\/wp\/v2\/kbtag?post=4219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}